{"id":36,"date":"2022-06-21T18:17:57","date_gmt":"2022-06-21T16:17:57","guid":{"rendered":"https:\/\/www.travelcompositor.com\/?page_id=36"},"modified":"2026-03-26T12:41:52","modified_gmt":"2026-03-26T11:41:52","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/travelcompositor.com\/en\/contact-us\/","title":{"rendered":"Contact us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"36\" class=\"elementor elementor-36\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8cf1316 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"8cf1316\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3166d7a\" data-id=\"3166d7a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea6af2a elementor-widget elementor-widget-google_maps\" data-id=\"ea6af2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Carrer%20de%20Cal%C3%A7at%2C%206%2C%20Ponent%2C%2007011%20Palma%2C%20Illes%20Balears&#038;t=m&#038;z=11&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Carrer de Cal\u00e7at, 6, Ponent, 07011 Palma, Illes Balears\"\n\t\t\t\t\taria-label=\"Carrer de Cal\u00e7at, 6, Ponent, 07011 Palma, Illes Balears\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efbea4a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efbea4a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27e3229\" data-id=\"27e3229\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e4fa3d elementor-widget elementor-widget-spacer\" data-id=\"7e4fa3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131f678 orb_headings elementor-align-center orb_headings elementor-mobile-align-left elementor-widget elementor-widget-ori-heading\" data-id=\"131f678\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h1 class=\"orb_heading \">Still wanting more? <\/h1>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6de6670 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6de6670\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8f26c82\" data-id=\"8f26c82\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-178b7cb orb_paragraphs elementor-align-center orb_paragraphs elementor-mobile-align-left workBreaks-no elementor-widget elementor-widget-ori-text\" data-id=\"178b7cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"orb_paragraph\">Fill out this form, we will be happy to assist you and tell you more about our services, products and solutions.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79121c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79121c6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b432bce\" data-id=\"b432bce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3988eee contact_align elementor-align-left elementor-widget elementor-widget-ori-contact-form\" data-id=\"3988eee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"contactForm\">                                    <h3 class=\"widgetTitle\">Contact us<\/h3>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f4989-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"4989\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/36#wpcf7-f4989-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"4989\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4989-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-610\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name and surname\" value=\"\" type=\"text\" name=\"text-610\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-lg-6\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-150\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your email\" value=\"\" type=\"email\" name=\"email-150\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\n <!-- Campo Prefix y Pa\u00eds en la misma fila -->\n\t<div class=\"col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"prefix-tel-838\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Prefix\" value=\"\" type=\"text\" name=\"prefix-tel-838\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-29\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Telephone number\" value=\"\" type=\"tel\" name=\"tel-29\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country-910\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Country\" value=\"\" type=\"text\" name=\"country-910\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-lg-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-612\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"text-612\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-lg-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-298\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Write your message here\" name=\"textarea-298\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6LefTo4nAAAAACHmDQidSINo1igv2F9nezobfJM3\" class=\"wpcf7-form-control wpcf7-recaptcha g-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe src=\"https:\/\/www.google.com\/recaptcha\/api\/fallback?k=6LefTo4nAAAAACHmDQidSINo1igv2F9nezobfJM3\" frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"checkbox-79\"><span class=\"wpcf7-form-control wpcf7-checkbox wpcf7-validates-as-required\"><span class=\"wpcf7-list-item first last\"><label><input type=\"checkbox\" name=\"checkbox-79[]\" value=\"Accept Privacy Policy\" \/><span class=\"wpcf7-list-item-label\">Accept Privacy Policy<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<div class=\"col-lg-12\">\n\t\t<p><button type=\"submit\" class=\"orbBtn01\"><span class=\"bp-shape\"><\/span><span class=\"bp-shape\"><\/span><span class=\"bp-shape\"><\/span><span class=\"bp-shape\"><\/span><span class=\"bp-text\">Send to<\/span><\/button>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"161\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb1f393 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fb1f393\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1e9a628\" data-id=\"1e9a628\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2057c2 orb_headings elementor-align-center orb_headings elementor-mobile-align-center elementor-widget elementor-widget-ori-heading\" data-id=\"d2057c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h2 class=\"orb_heading secTitle\">Our offices around the world<\/h2>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a9e68d0 e-grid e-con-boxed e-con e-parent\" data-id=\"a9e68d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b33c7b5 e-con-full e-flex e-con e-child\" data-id=\"b33c7b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28885e6 elementor-widget elementor-widget-google_maps\" data-id=\"28885e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Carrer%20de%20Cal%C3%A7at%2C%206%2C%20Ponent%2C%2007011%20Palma%2C%20Illes%20Balears&#038;t=m&#038;z=11&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Carrer de Cal\u00e7at, 6, Ponent, 07011 Palma, Illes Balears\"\n\t\t\t\t\taria-label=\"Carrer de Cal\u00e7at, 6, Ponent, 07011 Palma, Illes Balears\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5da4718 e-con-full e-flex e-con e-child\" data-id=\"5da4718\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e899fd3 orb_headings elementor-align-left elementor-widget elementor-widget-ori-heading\" data-id=\"e899fd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h2 class=\"orb_heading secTitle\"><h3>Headquarters  <\/h3><\/h2>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-862d5c6 elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"862d5c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pol\u00edgono Son Valent\u00ed, Calle de Cal\u00e7at, 6, 3rd floor, Palma de Mallorca<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>T. +34 971 55 72 43<\/b> <br> <a href=\"mailto:info@travelcompositor.com\">info@travelcompositor.com<\/a><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Opening hours:<\/b> <br>From Monday to Friday<br>  10.00h - 19.00h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11e8fdb e-con-full e-flex e-con e-child\" data-id=\"11e8fdb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78f0a17 elementor-widget elementor-widget-google_maps\" data-id=\"78f0a17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Av.%20Cob%C3%A1%20%7C%20Edificio%20Kukulc%C3%A1n%20No%2082%2C%20SM3%20MZ10.%2077500%20%7C%20Piso%203%20-%20Oficina%20%237&#038;t=m&#038;z=11&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Av. Cob\u00e1 | Edificio Kukulc\u00e1n No 82, SM3 MZ10. 77500 | Piso 3 - Oficina #7\"\n\t\t\t\t\taria-label=\"Av. Cob\u00e1 | Edificio Kukulc\u00e1n No 82, SM3 MZ10. 77500 | Piso 3 - Oficina #7\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-157b9af e-con-full e-flex e-con e-child\" data-id=\"157b9af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4ec96 orb_headings elementor-align-left elementor-widget elementor-widget-ori-heading\" data-id=\"dd4ec96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h2 class=\"orb_heading secTitle\"><h3>Canc\u00fan - Mexico<\/h3><\/h2>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d9353 elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"54d9353\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Cob\u00e1 | Edificio Kukulc\u00e1n No 82, SM3 MZ10. 77500 | Piso 3 - Oficina #7<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b> T. +52 998 626 1376<\/b> <br><a href=\"mailto:info@travelcompositor.com\">info@travelcompositor.com<\/a><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Opening hours:<\/b> <br>From Monday to Friday<br>  10.00h - 19.00h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9546eeb elementor-widget elementor-widget-google_maps\" data-id=\"9546eeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=2332%20Galiano%20Street%20%202nd%20Floor%20Coral%20Gable%20%2033134%20USA&#038;t=m&#038;z=11&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"2332 Galiano Street  2nd Floor Coral Gable  33134 USA\"\n\t\t\t\t\taria-label=\"2332 Galiano Street  2nd Floor Coral Gable  33134 USA\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9737912 e-con-full e-flex e-con e-child\" data-id=\"9737912\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7a4bf7 orb_headings elementor-align-left elementor-widget elementor-widget-ori-heading\" data-id=\"a7a4bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h2 class=\"orb_heading secTitle\"><h3>Miami - EEUU<\/h3><\/h2>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5fa8d elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"5e5fa8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2332 Galiano Street  2nd Floor Coral Gable  33134 USA<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>T. +1 786 2308735<\/b><b> <br>T. +1 883 4223235<\/b> <a href=\"mailto:info@travelcompositor.com\">info@travelcompositor.com<\/a> <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Opening hours:<\/b> <br>From Monday to Friday<br>  08.00h - 16.00h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d8dba90 e-con-full e-flex e-con e-child\" data-id=\"d8dba90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4cbeac8 elementor-widget elementor-widget-google_maps\" data-id=\"4cbeac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Av.%20Paulista%2C%202202%20-%20Consola%C3%A7%C3%A3o%2C%20S%C3%A3o%20Paulo%20-%20SP%2C%2001310-300&#038;t=m&#038;z=11&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Av. Paulista, 2202 - Consola\u00e7\u00e3o, S\u00e3o Paulo - SP, 01310-300\"\n\t\t\t\t\taria-label=\"Av. Paulista, 2202 - Consola\u00e7\u00e3o, S\u00e3o Paulo - SP, 01310-300\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b65c58 e-con-full e-flex e-con e-child\" data-id=\"3b65c58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb26dc orb_headings elementor-align-left elementor-widget elementor-widget-ori-heading\" data-id=\"1fb26dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ori-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <h2 class=\"orb_heading secTitle\"><h3>S\u00e3o Paulo - Brasil<\/h3><\/h2>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c33207c elementor-align-start elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c33207c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Av. Paulista, 2202 - Consola\u00e7\u00e3o, S\u00e3o Paulo - SP, 01310-300<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b> T. +55 11 94497-3080<\/b> <br><a href=\"mailto:info@travelcompositor.com\">info@travelcompositor.com<\/a><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Opening hours:<\/b> <br>From Monday to Friday<br>  10.00h - 19.00h<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-809d471 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"809d471\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4eb375e\" data-id=\"4eb375e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e699ca1 elementor-widget elementor-widget-spacer\" data-id=\"e699ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Still wanting more? Fill out this form, we will be happy to assist you and tell you more about our services, products and solutions. Contact us Accept Privacy Policy Send to &#916; Our offices around the world Headquarters Pol\u00edgono Son Valent\u00ed, Calle de Cal\u00e7at, 6, 3rd floor, Palma de Mallorca T. +34 971 55 72 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-36","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact us | Travel Compositor<\/title>\n<meta name=\"description\" content=\"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelcompositor.com\/en\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact us | Travel Compositor\" \/>\n<meta property=\"og:description\" content=\"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelcompositor.com\/en\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel Compositor\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T11:41:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelcompositor.com\/wp-content\/uploads\/2023\/04\/travelcompositor-web-demo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TravelC_online\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/contact-us\\\/\",\"url\":\"https:\\\/\\\/travelcompositor.com\\\/contact-us\\\/\",\"name\":\"Contact us | Travel Compositor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#website\"},\"datePublished\":\"2022-06-21T16:17:57+00:00\",\"dateModified\":\"2026-03-26T11:41:52+00:00\",\"description\":\"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/contact-us\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/travelcompositor.com\\\/contact-us\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/contact-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/travelcompositor.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/\",\"name\":\"Travel Compositor - The Holistic System by TravelSoft\",\"description\":\"El \u00fanico sistema Hol\u00edstico de venta de viajes. nuestra tecnolog\u00eda ofrece todos los servicios necesarios para un viaje en una sola sesi\u00f3n y pago. Porque tenemos un modelo disponible para cada tipo de empresas de turismo, viajes y ocio. Porque ofrecemos un mundo servicios y valores a\u00f1adidos alrededor de la tecnolog\u00eda convirtiendonos en algo m\u00e1s que un proveedor, un generador de negocio y tu mejor socio para tu \u00e9xito y crecimiento.\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#organization\"},\"alternateName\":\"Travel Compositor - The Holistic System by TravelSoft\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#organization\",\"name\":\"Travel Compositor\",\"alternateName\":\"TravelC\",\"url\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelcompositor.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotravelcompositor.png\",\"contentUrl\":\"https:\\\/\\\/travelcompositor.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logotravelcompositor.png\",\"width\":589,\"height\":144,\"caption\":\"Travel Compositor\"},\"image\":{\"@id\":\"https:\\\/\\\/travelcompositor.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/TravelC_online\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/travelcompositor\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7fnIOjOmM55eHolZtlIpsw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact us | Travel Compositor","description":"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelcompositor.com\/en\/contact-us\/","og_locale":"en_GB","og_type":"article","og_title":"Contact us | Travel Compositor","og_description":"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.","og_url":"https:\/\/travelcompositor.com\/en\/contact-us\/","og_site_name":"Travel Compositor","article_modified_time":"2026-03-26T11:41:52+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/travelcompositor.com\/wp-content\/uploads\/2023\/04\/travelcompositor-web-demo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TravelC_online","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/travelcompositor.com\/contact-us\/","url":"https:\/\/travelcompositor.com\/contact-us\/","name":"Contact us | Travel Compositor","isPartOf":{"@id":"https:\/\/travelcompositor.com\/es\/#website"},"datePublished":"2022-06-21T16:17:57+00:00","dateModified":"2026-03-26T11:41:52+00:00","description":"Technological solutions for travel agency networks, tour operators, OTAs and DMCs. Power your business with our tools.","breadcrumb":{"@id":"https:\/\/travelcompositor.com\/contact-us\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/travelcompositor.com\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/travelcompositor.com\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/travelcompositor.com\/"},{"@type":"ListItem","position":2,"name":"Contact us"}]},{"@type":"WebSite","@id":"https:\/\/travelcompositor.com\/es\/#website","url":"https:\/\/travelcompositor.com\/es\/","name":"Travel Compositor - The Holistic System by TravelSoft","description":"El \u00fanico sistema Hol\u00edstico de venta de viajes. nuestra tecnolog\u00eda ofrece todos los servicios necesarios para un viaje en una sola sesi\u00f3n y pago. Porque tenemos un modelo disponible para cada tipo de empresas de turismo, viajes y ocio. Porque ofrecemos un mundo servicios y valores a\u00f1adidos alrededor de la tecnolog\u00eda convirtiendonos en algo m\u00e1s que un proveedor, un generador de negocio y tu mejor socio para tu \u00e9xito y crecimiento.","publisher":{"@id":"https:\/\/travelcompositor.com\/es\/#organization"},"alternateName":"Travel Compositor - The Holistic System by TravelSoft","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelcompositor.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/travelcompositor.com\/es\/#organization","name":"Travel Compositor","alternateName":"TravelC","url":"https:\/\/travelcompositor.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/travelcompositor.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/travelcompositor.com\/wp-content\/uploads\/2022\/06\/logotravelcompositor.png","contentUrl":"https:\/\/travelcompositor.com\/wp-content\/uploads\/2022\/06\/logotravelcompositor.png","width":589,"height":144,"caption":"Travel Compositor"},"image":{"@id":"https:\/\/travelcompositor.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/TravelC_online","https:\/\/www.linkedin.com\/company\/travelcompositor\/","https:\/\/www.youtube.com\/channel\/UC7fnIOjOmM55eHolZtlIpsw"]}]}},"_links":{"self":[{"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/pages\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":126,"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/pages\/36\/revisions"}],"predecessor-version":[{"id":16681,"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/pages\/36\/revisions\/16681"}],"wp:attachment":[{"href":"https:\/\/travelcompositor.com\/en\/wp-json\/wp\/v2\/media?parent=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}